{"id":1093,"date":"2022-12-09T11:07:08","date_gmt":"2022-12-09T10:07:08","guid":{"rendered":"https:\/\/www.gammasystem.com\/?page_id=1093"},"modified":"2023-03-06T15:27:15","modified_gmt":"2023-03-06T14:27:15","slug":"pulsanteria-di-emergenza-e-bimanuali","status":"publish","type":"page","link":"https:\/\/www.gammasystem.com\/fr\/pulsanteria-di-emergenza-e-bimanuali\/","title":{"rendered":"Panneau d'urgence et commandes bimanuelles"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1093\" class=\"elementor elementor-1093\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff0d609 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ff0d609\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-612bda3\" data-id=\"612bda3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3466fd5 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3466fd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pulsanti di emergenza e bimanuali<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a828c5a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a828c5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f019f9\" data-id=\"9f019f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ba499c elementor-widget elementor-widget-text-editor\" data-id=\"9ba499c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I <strong>pulsanti di arresto di emergenza<\/strong> sono dispositivi di sicurezza progettati per interrompere rapidamente e in modo sicuro l&#8217;alimentazione elettrica o il funzionamento di una macchina o di un impianto in caso di emergenza.<\/p><p>L&#8217;utilizzo di questi pulsanti pu\u00f2 aiutare a <strong>prevenire lesioni alle persone, danni alle propriet\u00e0<\/strong> e interruzioni della produzione.<\/p><p>In macchine o impianti industriali <strong>\u00e8 obbligatorio installare questi pulsanti di emergenza<\/strong>, per garantire la sicurezza degli operatori e delle persone che potrebbero essere presenti nell&#8217;area di lavoro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1699f735 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1699f735\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c311c1e\" data-id=\"7c311c1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195a83d6 elementor-widget elementor-widget-heading\" data-id=\"195a83d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">I pulsanti di emergenza proposti da Gamma System sono i pi\u00f9 moderni e affidabili presenti nel mercato della sicurezza industriale. <br>Il pulsante ad aggancio con sgancio a rotazione ha una fascia verde laterale per l\u2019indicazione fisica dello stato (APERTO o CHIUSO).<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-584690e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"584690e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2e1d30\" data-id=\"a2e1d30\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db0c334 elementor-widget elementor-widget-heading\" data-id=\"4db0c334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il pulsante di emergenza  a fungo, pu\u00f2 essere fornito in 2 versioni:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23c516aa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"23c516aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-64d975b9\" data-id=\"64d975b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9698c0 elementor-widget elementor-widget-text-editor\" data-id=\"d9698c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><b>Sciolta:<\/b>\u00a0da completare a cura dell\u2019utilizzatore con flangia di connessione e relativi contatti NC ed NA (possono essere montati fino ad un massimo di 6 contatti per operatore). In particolare \u00e8 disponibile un contatto speciale composto da un NC collegato in serie ad un NA. La chiusura di quest\u2019ultimo grazie ad un sofisticato sistema meccanico ad azione positiva, avviene solo quando il blocco \u00e8 connesso con l\u2019operatore per assicurare la funzione d\u2019intervento anche in caso di sgancio dell\u2019operatore stesso.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cdfdbac\" data-id=\"cdfdbac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8d5a6f elementor-widget elementor-widget-text-editor\" data-id=\"c8d5a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><b>Montata:<\/b>\u00a0in cassetta con dimensioni 65 x 65 mm in materiale termoplastico o alluminio entrambi con grado di protezione IP65.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d0921 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"34d0921\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39b9daf\" data-id=\"39b9daf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be5939f elementor-widget elementor-widget-text-editor\" data-id=\"be5939f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono anche disponibili targhette rotonde di diametro 60 o 90 mm con scritta EMERGENCY STOP o ARRESTO EMERGENZA e\/o supporti porta-targhetta.<\/p><p>Completa l\u2019offerta un controllo bimanuale dal design ergonomico e moderno di dimensioni compatte (380 x 90 x 90 mm) per una facile installazione anche su macchine operatrici di piccole dimensioni. La bimanuale \u00e8 disponibile in versione completa, oltre che dai due pulsanti laterali, di pulsante a fungo arresto d\u2019emergenza. Per entrambi i prodotti pu\u00f2 essere fornita la relativa centralina in grado di sicurezza 4.<\/p><p>Norma di riferimento\u00a0<b>EN 60947-5-1 e IEC 947-5-1.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd335b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0bd335b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b553585\" data-id=\"b553585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a10fdc elementor-widget elementor-widget-heading\" data-id=\"5a10fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contattaci <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b93e3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f0b93e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6acab58 elementor-widget elementor-widget-text-editor\" data-id=\"6acab58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCompila il form ti risponderemo <br>entro 24 ore.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-815eb83\" data-id=\"815eb83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-020ae5d elementor-widget elementor-widget-shortcode\" data-id=\"020ae5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"everest-forms\"><div class=\"evf-container default\" id=\"evf-236\"><form id=\"evf-form-236\" class=\"everest-form\" data-formid=\"236\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" data-form_state_type=\"\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/1093\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce236\" name=\"_wpnonce236\" value=\"154db4044f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/pages\/1093\" \/><div class=\"evf-frontend-row\" data-row=\"row_1\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-236-field_fullname-container\" class=\"evf-field evf-field-text form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"fullname\"><label class=\"evf-field-label\" for=\"evf-236-field_fullname\"><span class=\"evf-label\">Nome e cognome<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"text\" id=\"evf-236-field_fullname\" class=\"input-text\" name=\"everest_forms[form_fields][fullname]\" required><\/div><div id=\"evf-236-field_email-container\" class=\"evf-field evf-field-email form-row validate-required validate-email\" data-required-field-message=\"Please enter a valid email address.\" data-field-id=\"email\"><label class=\"evf-field-label\" for=\"evf-236-field_email\"><span class=\"evf-label\">Email<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"email\" id=\"evf-236-field_email\" class=\"input-text\" name=\"everest_forms[form_fields][email]\" required ><\/div><div id=\"evf-236-field_message-container\" class=\"evf-field evf-field-textarea form-row\" data-field-id=\"message\"><label class=\"evf-field-label\" for=\"evf-236-field_message\"><span class=\"evf-label\">Messaggio<\/span> <\/label><textarea id=\"evf-236-field_message\" class=\"input-text\" name=\"everest_forms[form_fields][message]\"  ><\/textarea><\/div><div id=\"evf-236-field_Fa2qggVzJs-1-container\" class=\"evf-field evf-field-checkbox form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"Fa2qggVzJs-1\"><label class=\"evf-field-label\" for=\"evf-236-field_Fa2qggVzJs-1\"><span class=\"evf-label\">Trattamento dati<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><ul id=\"evf-236-field_Fa2qggVzJs-1\" class=\" evf-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"evf-236-field_Fa2qggVzJs-1_1\" class=\"input-text\" name=\"everest_forms[form_fields][Fa2qggVzJs-1][]\" value=\"Ho preso visione dell\u2019informativa Privacy\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-236-field_Fa2qggVzJs-1_1\">Ho preso visione dell\u2019informativa Privacy<\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_2\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-236-field_IWX5HFxv2j-18-container\" class=\"evf-field evf-field-recaptcha form-row\" data-field-id=\"IWX5HFxv2j-18\"><div class=\"evf-recaptcha-container \" style=\"display:block\"><div class=\"g-recaptcha\" data-sitekey=\"6LfrSpQrAAAAAHpPYcvfmcqVN9-pGlhhucpJZw3D\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-236-field-hp\" class=\"evf-field-label\">Website<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-236-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"236\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"129\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-236' value='evf-submit' data-process-text=\"invio\u2026\" conditional_rules='&quot;&quot;' conditional_id='evf-submit-236'  id=\"evf-submit-236\" aria-live=\"assertive\">Invio<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pulsanti di emergenza e bimanuali I pulsanti di arresto di emergenza sono dispositivi di sicurezza progettati per interrompere rapidamente e in modo sicuro l&#8217;alimentazione elettrica o il funzionamento di una macchina o di un impianto in caso di emergenza. L&#8217;utilizzo di questi pulsanti pu\u00f2 aiutare a prevenire lesioni alle persone, danni alle propriet\u00e0 e interruzioni della produzione. In macchine o impianti industriali \u00e8 obbligatorio installare questi pulsanti di emergenza, per garantire la sicurezza degli operatori e delle persone che potrebbero essere presenti nell&#8217;area di lavoro. I pulsanti di emergenza proposti da Gamma System sono i pi\u00f9 moderni e affidabili presenti nel mercato della sicurezza industriale. Il pulsante ad aggancio con sgancio a rotazione ha una fascia verde laterale per l\u2019indicazione fisica dello stato (APERTO o CHIUSO). Il pulsante di emergenza a fungo, pu\u00f2 essere fornito in 2 versioni: Sciolta:\u00a0da completare a cura dell\u2019utilizzatore con flangia di connessione e relativi contatti NC ed NA (possono essere montati fino ad un massimo di 6 contatti per operatore). In particolare \u00e8 disponibile un contatto speciale composto da un NC collegato in serie ad un NA. La chiusura di quest\u2019ultimo grazie ad un sofisticato sistema meccanico ad azione positiva, avviene solo quando il blocco \u00e8 connesso con l\u2019operatore per assicurare la funzione d\u2019intervento anche in caso di sgancio dell\u2019operatore stesso. Montata:\u00a0in cassetta con dimensioni 65 x 65 mm in materiale termoplastico o alluminio entrambi con grado di protezione IP65. Sono anche disponibili targhette rotonde di diametro 60 o 90 mm con scritta EMERGENCY STOP o ARRESTO EMERGENZA e\/o supporti porta-targhetta. Completa l\u2019offerta un controllo bimanuale dal design ergonomico e moderno di dimensioni compatte (380 x 90 x 90 mm) per una facile installazione anche su macchine operatrici di piccole dimensioni. La bimanuale \u00e8 disponibile in versione completa, oltre che dai due pulsanti laterali, di pulsante a fungo arresto d\u2019emergenza. Per entrambi i prodotti pu\u00f2 essere fornita la relativa centralina in grado di sicurezza 4. Norma di riferimento\u00a0EN 60947-5-1 e IEC 947-5-1. Contattaci Compila il form ti risponderemo entro 24 ore.<\/p>","protected":false},"author":129,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1093","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pulsanti di emergenza | Gamma System<\/title>\n<meta name=\"description\" content=\"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gammasystem.com\/fr\/pulsanteria-di-emergenza-e-bimanuali\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pulsanti di emergenza | Gamma System\" \/>\n<meta property=\"og:description\" content=\"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gammasystem.com\/fr\/pulsanteria-di-emergenza-e-bimanuali\/\" \/>\n<meta property=\"og:site_name\" content=\"Gamma System\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T14:27:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/pulsanteria-di-emergenza-e-bimanuali\\\/\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/pulsanteria-di-emergenza-e-bimanuali\\\/\",\"name\":\"Pulsanti di emergenza | Gamma System\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#website\"},\"datePublished\":\"2022-12-09T10:07:08+00:00\",\"dateModified\":\"2023-03-06T14:27:15+00:00\",\"description\":\"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gammasystem.com\\\/pulsanteria-di-emergenza-e-bimanuali\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/\",\"name\":\"Gamma System\",\"description\":\"Sistemi per la Sicurezza Industriale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gammasystem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#organization\",\"name\":\"Gamma System\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Schermata-2022-07-11-alle-17.07.23.png\",\"contentUrl\":\"https:\\\/\\\/www.gammasystem.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Schermata-2022-07-11-alle-17.07.23.png\",\"width\":400,\"height\":226,\"caption\":\"Gamma System\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pulsanti di emergenza | Gamma System","description":"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gammasystem.com\/fr\/pulsanteria-di-emergenza-e-bimanuali\/","og_locale":"fr_FR","og_type":"article","og_title":"Pulsanti di emergenza | Gamma System","og_description":"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.","og_url":"https:\/\/www.gammasystem.com\/fr\/pulsanteria-di-emergenza-e-bimanuali\/","og_site_name":"Gamma System","article_modified_time":"2023-03-06T14:27:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gammasystem.com\/pulsanteria-di-emergenza-e-bimanuali\/","url":"https:\/\/www.gammasystem.com\/pulsanteria-di-emergenza-e-bimanuali\/","name":"Pulsanti di emergenza | Gamma System","isPartOf":{"@id":"https:\/\/www.gammasystem.com\/#website"},"datePublished":"2022-12-09T10:07:08+00:00","dateModified":"2023-03-06T14:27:15+00:00","description":"I pulsanti di arresto di emergenza sono dispositivi di sicurezza che interrompono il funzionamento di una macchina in caso di emergenza.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gammasystem.com\/pulsanteria-di-emergenza-e-bimanuali\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.gammasystem.com\/#website","url":"https:\/\/www.gammasystem.com\/","name":"Gamma System","description":"Sistemi per la Sicurezza Industriale","publisher":{"@id":"https:\/\/www.gammasystem.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gammasystem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.gammasystem.com\/#organization","name":"Gamma System","url":"https:\/\/www.gammasystem.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gammasystem.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gammasystem.com\/wp-content\/uploads\/2022\/07\/Schermata-2022-07-11-alle-17.07.23.png","contentUrl":"https:\/\/www.gammasystem.com\/wp-content\/uploads\/2022\/07\/Schermata-2022-07-11-alle-17.07.23.png","width":400,"height":226,"caption":"Gamma System"},"image":{"@id":"https:\/\/www.gammasystem.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/pages\/1093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/comments?post=1093"}],"version-history":[{"count":38,"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/pages\/1093\/revisions"}],"predecessor-version":[{"id":2007,"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/pages\/1093\/revisions\/2007"}],"wp:attachment":[{"href":"https:\/\/www.gammasystem.com\/fr\/wp-json\/wp\/v2\/media?parent=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}