{"id":1102,"date":"2022-12-09T11:10:55","date_gmt":"2022-12-09T10:10:55","guid":{"rendered":"https:\/\/www.gammasystem.com\/?page_id=1102"},"modified":"2023-03-06T15:28:40","modified_gmt":"2023-03-06T14:28:40","slug":"finecorsa-meccanici-sensori-magnetici-e-centraline","status":"publish","type":"page","link":"https:\/\/www.gammasystem.com\/de\/finecorsa-meccanici-sensori-magnetici-e-centraline\/","title":{"rendered":"Mechanische endschalter, Magnetische sensoren und Steuerger\u00e4te"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1102\" class=\"elementor elementor-1102\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86a8221 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"86a8221\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e68ae3\" data-id=\"4e68ae3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2436e1d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2436e1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Finecorsa meccanici, sensori magnetici e centraline\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1699f735 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1699f735\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c311c1e\" data-id=\"7c311c1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195a83d6 elementor-widget elementor-widget-heading\" data-id=\"195a83d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">\u00c8 disponibile una serie completa di prodotti destinati <br>al controllo della chiusura di porte, ripari o protezioni mobili in versione meccanica o magnetica. <br>I modelli meccanici offrono vantaggi particolari quali visibilit\u00e0 del funzionamento, contatti elettricamente separati ed in grado di commutare elevate correnti.<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-584690e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"584690e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2e1d30 elementor-invisible\" data-id=\"a2e1d30\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23c516aa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"23c516aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-64d975b9\" data-id=\"64d975b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9698c0 elementor-widget elementor-widget-text-editor\" data-id=\"d9698c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I <strong>finecorsa meccanici<\/strong> sono dispositivi utilizzati per determinare la posizione di fine corsa di un movimento meccanico.<\/p><p>Vengono utilizzati per limitare la corsa di un&#8217;attuatore o di un meccanismo di trasmissione, in modo da <strong>evitare danni alle attrezzature o pericoli per gli operatori<\/strong>.<\/p><p>Funzionano in base a un principio di <strong>contatto fisico<\/strong>: quando il meccanismo si muove e raggiunge la posizione di fine corsa, il dispositivo entra in contatto con il punto di fine corsa e <strong>interrompe il movimento<\/strong>, impedendo ulteriori spostamenti.<\/p><p>I <strong>finecorsa meccanici Gamma System<\/strong> possono essere forniti in versione con custodia in <strong>plastica IP65<\/strong> o <strong>metallo IP66<\/strong> con larghezza 30 o 50 mm in tre configurazioni:<\/p><ol><li><strong>a chiave<\/strong> (sono disponibili diversi tipi di chiave) a testa regolabile a 90\u00b0;<\/li><li>con albero in <strong>acciaio zincato<\/strong>;<\/li><li><strong>a leva in acciaio zincato<\/strong>. I moduli vanno completati con i relativi blocchi di contatti ausiliari a scatto (1NA + 1NC oppure 2 NC).<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4db0c334 elementor-widget elementor-widget-heading\" data-id=\"4db0c334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c8 disponibile la relativa centralina di sicurezza in categoria 4.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d0921 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"34d0921\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39b9daf\" data-id=\"39b9daf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be5939f elementor-widget elementor-widget-text-editor\" data-id=\"be5939f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I <strong>finecorsa magnetici<\/strong>, da preferire nel caso di utilizzo in ambienti particolarmente umidi, sporchi o polverosi, tutti con grado di <strong>protezione IP67<\/strong>, sono disponibili in <strong>2 configurazioni geometriche:<\/strong><\/p><ul><li>cilindrica (con diametro 6 mm);<\/li><li>rettangolare (67 x 25 mm o 48 x 40 mm) con relativo magnete d\u2019attivazione.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1d4729 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d1d4729\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a619010 elementor-invisible\" data-id=\"a619010\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-922ec9c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"922ec9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1dc3785\" data-id=\"1dc3785\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9026e83 elementor-widget elementor-widget-text-editor\" data-id=\"9026e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tutti i modelli di finecorsa dispongono di un <b>contatto NA ed un contatto NC in uscita<\/b>. L\u2019attivazione del sensore pu\u00f2 avvenire indifferentemente lungo i tre assi &#8220;X&#8221;, &#8220;Y&#8221; e &#8220;Z&#8221; e si realizza attraverso l\u2019avvicinamento dell\u2019unit\u00e0 magnetica.<\/p><p>Sono previsti riferimenti serigrafici e meccanici per il corretto montaggio e funzionamento. Sono disponibili 2 diversi tipi di centralina di sicurezza in categoria 4 a seconda del numero di sensori collegati (fino ad un massimo di 6 sensori con ingresso indipendente).<\/p><p>Norma di riferimento\u00a0<b>EN 60947-5-1 e IEC 947-5-1.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd335b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0bd335b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b553585\" data-id=\"b553585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a10fdc elementor-widget elementor-widget-heading\" data-id=\"5a10fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contattaci <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b93e3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f0b93e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6acab58 elementor-widget elementor-widget-text-editor\" data-id=\"6acab58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCompila il form ti risponderemo <br>entro 24 ore.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-815eb83\" data-id=\"815eb83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-020ae5d elementor-widget elementor-widget-shortcode\" data-id=\"020ae5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"everest-forms\"><div class=\"evf-container default\" id=\"evf-236\"><form id=\"evf-form-236\" class=\"everest-form\" data-formid=\"236\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" data-form_state_type=\"\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/1102\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce236\" name=\"_wpnonce236\" value=\"154db4044f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/pages\/1102\" \/><div class=\"evf-frontend-row\" data-row=\"row_1\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-236-field_fullname-container\" class=\"evf-field evf-field-text form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"fullname\"><label class=\"evf-field-label\" for=\"evf-236-field_fullname\"><span class=\"evf-label\">Nome e cognome<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"text\" id=\"evf-236-field_fullname\" class=\"input-text\" name=\"everest_forms[form_fields][fullname]\" required><\/div><div id=\"evf-236-field_email-container\" class=\"evf-field evf-field-email form-row validate-required validate-email\" data-required-field-message=\"Please enter a valid email address.\" data-field-id=\"email\"><label class=\"evf-field-label\" for=\"evf-236-field_email\"><span class=\"evf-label\">Email<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"email\" id=\"evf-236-field_email\" class=\"input-text\" name=\"everest_forms[form_fields][email]\" required ><\/div><div id=\"evf-236-field_message-container\" class=\"evf-field evf-field-textarea form-row\" data-field-id=\"message\"><label class=\"evf-field-label\" for=\"evf-236-field_message\"><span class=\"evf-label\">Messaggio<\/span> <\/label><textarea id=\"evf-236-field_message\" class=\"input-text\" name=\"everest_forms[form_fields][message]\"  ><\/textarea><\/div><div id=\"evf-236-field_Fa2qggVzJs-1-container\" class=\"evf-field evf-field-checkbox form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"Fa2qggVzJs-1\"><label class=\"evf-field-label\" for=\"evf-236-field_Fa2qggVzJs-1\"><span class=\"evf-label\">Trattamento dati<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><ul id=\"evf-236-field_Fa2qggVzJs-1\" class=\" evf-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"evf-236-field_Fa2qggVzJs-1_1\" class=\"input-text\" name=\"everest_forms[form_fields][Fa2qggVzJs-1][]\" value=\"Ho preso visione dell\u2019informativa Privacy\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-236-field_Fa2qggVzJs-1_1\">Ho preso visione dell\u2019informativa Privacy<\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_2\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-236-field_IWX5HFxv2j-18-container\" class=\"evf-field evf-field-recaptcha form-row\" data-field-id=\"IWX5HFxv2j-18\"><div class=\"evf-recaptcha-container \" style=\"display:block\"><div class=\"g-recaptcha\" data-sitekey=\"6LfrSpQrAAAAAHpPYcvfmcqVN9-pGlhhucpJZw3D\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-236-field-hp\" class=\"evf-field-label\">Message<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-236-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"236\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"129\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-236' value='evf-submit' data-process-text=\"invio\u2026\" conditional_rules='&quot;&quot;' conditional_id='evf-submit-236'  id=\"evf-submit-236\" aria-live=\"assertive\">Invio<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Finecorsa meccanici, sensori magnetici e centraline \u00c8 disponibile una serie completa di prodotti destinati al controllo della chiusura di porte, ripari o protezioni mobili in versione meccanica o magnetica. I modelli meccanici offrono vantaggi particolari quali visibilit\u00e0 del funzionamento, contatti elettricamente separati ed in grado di commutare elevate correnti. I finecorsa meccanici sono dispositivi utilizzati per determinare la posizione di fine corsa di un movimento meccanico. Vengono utilizzati per limitare la corsa di un&#8217;attuatore o di un meccanismo di trasmissione, in modo da evitare danni alle attrezzature o pericoli per gli operatori. Funzionano in base a un principio di contatto fisico: quando il meccanismo si muove e raggiunge la posizione di fine corsa, il dispositivo entra in contatto con il punto di fine corsa e interrompe il movimento, impedendo ulteriori spostamenti. I finecorsa meccanici Gamma System possono essere forniti in versione con custodia in plastica IP65 o metallo IP66 con larghezza 30 o 50 mm in tre configurazioni: a chiave (sono disponibili diversi tipi di chiave) a testa regolabile a 90\u00b0; con albero in acciaio zincato; a leva in acciaio zincato. I moduli vanno completati con i relativi blocchi di contatti ausiliari a scatto (1NA + 1NC oppure 2 NC). \u00c8 disponibile la relativa centralina di sicurezza in categoria 4. I finecorsa magnetici, da preferire nel caso di utilizzo in ambienti particolarmente umidi, sporchi o polverosi, tutti con grado di protezione IP67, sono disponibili in 2 configurazioni geometriche: cilindrica (con diametro 6 mm); rettangolare (67 x 25 mm o 48 x 40 mm) con relativo magnete d\u2019attivazione. Tutti i modelli di finecorsa dispongono di un contatto NA ed un contatto NC in uscita. L\u2019attivazione del sensore pu\u00f2 avvenire indifferentemente lungo i tre assi &#8220;X&#8221;, &#8220;Y&#8221; e &#8220;Z&#8221; e si realizza attraverso l\u2019avvicinamento dell\u2019unit\u00e0 magnetica. Sono previsti riferimenti serigrafici e meccanici per il corretto montaggio e funzionamento. Sono disponibili 2 diversi tipi di centralina di sicurezza in categoria 4 a seconda del numero di sensori collegati (fino ad un massimo di 6 sensori con ingresso indipendente). Norma di riferimento\u00a0EN 60947-5-1 e IEC 947-5-1. Contattaci Compila il form ti risponderemo entro 24 ore.<\/p>","protected":false},"author":129,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1102","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finecorsa meccanici e sensori magnetici | Gamma System<\/title>\n<meta name=\"description\" content=\"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gammasystem.com\/de\/finecorsa-meccanici-sensori-magnetici-e-centraline\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finecorsa meccanici e sensori magnetici | Gamma System\" \/>\n<meta property=\"og:description\" content=\"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gammasystem.com\/de\/finecorsa-meccanici-sensori-magnetici-e-centraline\/\" \/>\n<meta property=\"og:site_name\" content=\"Gamma System\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T14:28:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/finecorsa-meccanici-sensori-magnetici-e-centraline\\\/\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/finecorsa-meccanici-sensori-magnetici-e-centraline\\\/\",\"name\":\"Finecorsa meccanici e sensori magnetici | Gamma System\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#website\"},\"datePublished\":\"2022-12-09T10:10:55+00:00\",\"dateModified\":\"2023-03-06T14:28:40+00:00\",\"description\":\"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gammasystem.com\\\/finecorsa-meccanici-sensori-magnetici-e-centraline\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/\",\"name\":\"Gamma System\",\"description\":\"Sistemi per la Sicurezza Industriale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gammasystem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#organization\",\"name\":\"Gamma System\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gammasystem.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Schermata-2022-07-11-alle-17.07.23.png\",\"contentUrl\":\"https:\\\/\\\/www.gammasystem.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Schermata-2022-07-11-alle-17.07.23.png\",\"width\":400,\"height\":226,\"caption\":\"Gamma System\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gammasystem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finecorsa meccanici e sensori magnetici | Gamma System","description":"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gammasystem.com\/de\/finecorsa-meccanici-sensori-magnetici-e-centraline\/","og_locale":"de_DE","og_type":"article","og_title":"Finecorsa meccanici e sensori magnetici | Gamma System","og_description":"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.","og_url":"https:\/\/www.gammasystem.com\/de\/finecorsa-meccanici-sensori-magnetici-e-centraline\/","og_site_name":"Gamma System","article_modified_time":"2023-03-06T14:28:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gammasystem.com\/finecorsa-meccanici-sensori-magnetici-e-centraline\/","url":"https:\/\/www.gammasystem.com\/finecorsa-meccanici-sensori-magnetici-e-centraline\/","name":"Finecorsa meccanici e sensori magnetici | Gamma System","isPartOf":{"@id":"https:\/\/www.gammasystem.com\/#website"},"datePublished":"2022-12-09T10:10:55+00:00","dateModified":"2023-03-06T14:28:40+00:00","description":"I finecorsa meccanici sono dispositivi che determinano la posizione di fine corsa di un movimento meccanico. Scopri le soluzioni Gamma System.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gammasystem.com\/finecorsa-meccanici-sensori-magnetici-e-centraline\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.gammasystem.com\/#website","url":"https:\/\/www.gammasystem.com\/","name":"Gamma System","description":"Sistemi per la Sicurezza Industriale","publisher":{"@id":"https:\/\/www.gammasystem.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gammasystem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gammasystem.com\/#organization","name":"Gamma System","url":"https:\/\/www.gammasystem.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gammasystem.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gammasystem.com\/wp-content\/uploads\/2022\/07\/Schermata-2022-07-11-alle-17.07.23.png","contentUrl":"https:\/\/www.gammasystem.com\/wp-content\/uploads\/2022\/07\/Schermata-2022-07-11-alle-17.07.23.png","width":400,"height":226,"caption":"Gamma System"},"image":{"@id":"https:\/\/www.gammasystem.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/pages\/1102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/comments?post=1102"}],"version-history":[{"count":25,"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/pages\/1102\/revisions"}],"predecessor-version":[{"id":2010,"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/pages\/1102\/revisions\/2010"}],"wp:attachment":[{"href":"https:\/\/www.gammasystem.com\/de\/wp-json\/wp\/v2\/media?parent=1102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}